{"id":104970,"date":"2021-12-24T12:19:13","date_gmt":"2021-12-24T11:19:13","guid":{"rendered":"https:\/\/www.monaco-tribune.com\/2021\/12\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\/"},"modified":"2022-01-22T18:02:58","modified_gmt":"2022-01-22T17:02:58","slug":"elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra","status":"publish","type":"post","link":"https:\/\/www.monaco-tribune.com\/it\/2021\/12\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\/","title":{"rendered":"Elizabeth Wessel: un ago in una mano, un pennello nell&#8217;altra"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><p><strong>Stilista e pittrice monegasca di origine danese, Elizabeth Wessel ha appena partecipato al Luxembourg Art Prize 2021.<\/strong><\/p><\/p>\n\n<p class=\"wp-block-paragraph\">Un grande orgoglio. \u00c8 questo quello che ha provato Elizabeth Wessel il 1\u00b0 dicembre, quando ha ricevuto il suo certificato di merito al concorso d&#8217;arte organizzato dalla Pinacoteca del Granducato di Lussemburgo.<\/p>\n\n<p class=\"wp-block-paragraph\">Un concorso che ogni anno riunisce diverse centinaia di artisti internazionali e al quale Elizabeth Wessel \u00e8 stata invitata. &#8220;Era la prima volta che partecipavo. \u00c8 stato molto bello, anche se non ho vinto. Sono felice di questo riconoscimento e parteciper\u00f2 di nuovo l&#8217;anno prossimo&#8221;, afferma l\u2019artista.<\/p>\n\n<p class=\"wp-block-paragraph\">Per l&#8217;occasione, Elizabeth Wessel ha presentato cinque opere. Cinque dipinti di diversi periodi, tra cui <em>No Limits<\/em>, che \u00e8 stato selezionato per partecipare alla Biennale Internazionale d&#8217;Arte di Pechino a gennaio.<\/p>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2021\/12\/capture-de&#x301;cran-2021-12-24-a&#x300;-12.09.53-670x1024.png\" alt=\"Elizabeth Wessel\" class=\"wp-image-104961\"\/><figcaption><em>&#8220;No limits&#8221; &#8211; DR<\/em><\/figcaption><\/figure><\/div>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Viaggiavamo molto con i miei genitori. (&#8230;) Ho passato la mia vita a disegnare.<\/p><\/blockquote>\n\n<h2 class=\"wp-block-heading\" id=\"h-passionnee-des-le-plus-jeune-age\">Appassionata d&#8217;arte fin da piccola<\/h2>\n\n<p class=\"wp-block-paragraph\">Per Elizabeth Wessel, questa vena artistica ha iniziato a svilupparsi gi\u00e0 dall&#8217;infanzia: &#8220;Viaggiavamo molto con i miei genitori. Alloggiavamo spesso in hotel e dato che all&#8217;epoca non c&#8217;erano videogiochi per passare il tempo, mi davano carta e matite colorate, cos\u00ec ho passato la mia vita a disegnare.&#8221;<\/p>\n\n<p class=\"wp-block-paragraph\">Una passione che si \u00e8 portata dietro anche a scuola e che non l&#8217;ha pi\u00f9 lasciata fino ai sedici anni. Appena diplomata, Elizabeth Wessel voleva diventare una stilista di moda e si iscrive all&#8217;\u00c9cole de la Chambre Syndicale de la Couture Parisienne, oggi diventata il nuovo Istituto francese di moda. Tre anni e una laurea dopo, la giovane danese fatica a trovare un posto, nonostante i suoi eccellenti risultati.<\/p>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"733\" src=\"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2021\/12\/5-ecole-de-la-chambre-syndicale-de-la-haute-couture-parisienne-1-1024x733.jpg\" alt=\"Elizabeth Wessel\" class=\"wp-image-104959\" srcset=\"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2021\/12\/5-ecole-de-la-chambre-syndicale-de-la-haute-couture-parisienne-1-1024x733.jpg 1024w, https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2021\/12\/5-ecole-de-la-chambre-syndicale-de-la-haute-couture-parisienne-1-419x300.jpg 419w, https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2021\/12\/5-ecole-de-la-chambre-syndicale-de-la-haute-couture-parisienne-1-210x150.jpg 210w, https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2021\/12\/5-ecole-de-la-chambre-syndicale-de-la-haute-couture-parisienne-1-768x550.jpg 768w, https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2021\/12\/5-ecole-de-la-chambre-syndicale-de-la-haute-couture-parisienne-1-175x125.jpg 175w, https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2021\/12\/5-ecole-de-la-chambre-syndicale-de-la-haute-couture-parisienne-1.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption><em>Ecole de la chambre syndicale de la couture parisienne &#8211; DR<\/em><\/figcaption><\/figure><\/div>\n\n<p class=\"wp-block-paragraph\">&#8220;Gli studenti francesi avevano la priorit\u00e0 nelle case di moda. Ho girato in lungo e in largo con i miei dossier e alla fine sono stata presa da Lapidus, poi da Torrente, e infine ho creato il mio marchio e ho aperto la mia boutique a Parigi&#8221;, ricorda l&#8217;artista. Qualche anno dopo, lascia la capitale per aprire una sede a Monaco e proporre le sue collezioni al mondo intero.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-une-reconnaissance-internationale\">Un riconoscimento internazionale<\/h2>\n\n<p class=\"wp-block-paragraph\">A poco a poco, il talento di Elizabeth Wessel comincia a farsi conoscere, soprattutto in Giappone, dove riscontra particolare successo e crea la sua licenza giapponese. &#8220;Andavo a Tokyo cinque volte l&#8217;anno, era fantastico! Quando c&#8217;\u00e8 stata la recessione, ho concluso il mio contratto e sono tornata a fare haute couture per una clientela mondana a Monaco.&#8221;<\/p>\n\n<p class=\"wp-block-paragraph\">A poco a poco, il talento di Elizabeth Wessel comincia a farsi conoscere, soprattutto in Giappone, dove riscontra particolare successo e crea la sua licenza giapponese. &#8220;Andavo a Tokyo cinque volte l&#8217;anno, era fantastico! Quando c&#8217;\u00e8 stata la recessione, ho concluso il mio contratto e sono tornata a fare haute couture per una clientela mondana a Monaco.&#8221;<\/p>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2021\/12\/68-une-a&#x302;me-denfant-polytique-7-panneaux-1024x437.jpg\" alt=\"Elizabeth Wessel\" class=\"wp-image-104965\"\/><figcaption><em>&#8220;Une \u00e2me d&#8217;enfant&#8221; &#8211; DR<\/em><\/figcaption><\/figure><\/div>\n\n<p class=\"wp-block-paragraph\">Nonostante le sue opere siano esposte in tutto il mondo, \u00e8 a Monaco che l&#8217;artista ha scelto di restare: &#8220;Mi piace il lato cosmopolita di Monaco e la vita \u00e8 molto piacevole. Per il mio lavoro di stilista, Parigi sarebbe pi\u00f9 semplice, \u00e8 vero. Ma per la pittura, vivere a Monaco non \u00e8 per niente un problema. \u00c8 un mondo diverso da quello della moda, tutto incentrato nella capitale.&#8221;<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>LEGGI ANCHE:<\/strong> <a href=\"https:\/\/www.monaco-tribune.com\/it\/2021\/11\/zhang-zhang-la-musica-puo-mettersi-al-servizio-di-qualsiasi-causa\/\">Zhang Zhang: \u201cLa musica pu\u00f2 mettersi al servizio di qualsiasi causa\u201d<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stilista e pittrice monegasca di origine danese, Elizabeth Wessel ha appena partecipato al Luxembourg Art Prize 2021. Un grande orgoglio. [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":104955,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1740,1826,1738],"tags":[],"post_sectags":[],"post_format":[2480],"class_list":["post-104970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosa-fare","category-la-nostra-scelta","category-notizie","format-profilo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Elizabeth Wessel: un ago in una mano, un pennello nell&#039;altra<\/title>\n<meta name=\"description\" content=\"Stilista e pittrice monegasca di origine danese, Elizabeth Wessel ha appena partecipato al Luxembourg Art Prize 2021. Un grande orgoglio. \u00c8 questo quello\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.monaco-tribune.com\/it\/2021\/12\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elizabeth Wessel: un ago in una mano, un pennello nell&#039;altra - Monaco Tribune\" \/>\n<meta property=\"og:description\" content=\"Stilista e pittrice monegasca di origine danese, Elizabeth Wessel ha appena partecipato al Luxembourg Art Prize 2021. Un grande orgoglio. \u00c8 questo quello\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.monaco-tribune.com\/it\/2021\/12\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\/\" \/>\n<meta property=\"og:site_name\" content=\"Monaco Tribune\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MonacoTribune\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-24T11:19:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-22T17:02:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2021\/12\/66-expo-ew-opera-gallery-hongkong.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Camille Esteve\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MonacoTribune\" \/>\n<meta name=\"twitter:site\" content=\"@MonacoTribune\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2021\\\/12\\\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2021\\\/12\\\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\\\/\"},\"author\":{\"name\":\"Camille Esteve\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#\\\/schema\\\/person\\\/a855d420fff4d03637641d60b93ac62e\"},\"headline\":\"Elizabeth Wessel: un ago in una mano, un pennello nell&#8217;altra\",\"datePublished\":\"2021-12-24T11:19:13+00:00\",\"dateModified\":\"2022-01-22T17:02:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2021\\\/12\\\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\\\/\"},\"wordCount\":564,\"publisher\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2021\\\/12\\\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/66-expo-ew-opera-gallery-hongkong.jpg\",\"articleSection\":[\"Cosa fare\",\"La nostra scelta\",\"Notizie\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2021\\\/12\\\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\\\/\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2021\\\/12\\\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\\\/\",\"name\":\"Elizabeth Wessel: un ago in una mano, un pennello nell'altra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2021\\\/12\\\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2021\\\/12\\\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/66-expo-ew-opera-gallery-hongkong.jpg\",\"datePublished\":\"2021-12-24T11:19:13+00:00\",\"dateModified\":\"2022-01-22T17:02:58+00:00\",\"description\":\"Stilista e pittrice monegasca di origine danese, Elizabeth Wessel ha appena partecipato al Luxembourg Art Prize 2021. Un grande orgoglio. \u00c8 questo quello\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2021\\\/12\\\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2021\\\/12\\\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2021\\\/12\\\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/66-expo-ew-opera-gallery-hongkong.jpg\",\"contentUrl\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/66-expo-ew-opera-gallery-hongkong.jpg\",\"width\":1200,\"height\":800,\"caption\":\"DR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2021\\\/12\\\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elizabeth Wessel: un ago in una mano, un pennello nell&rsquo;altra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/\",\"name\":\"Monaco Tribune\",\"description\":\"Monaco : actualit\u00e9s \u00e9conomiques, politiques, culturelles et sportives de Monaco et de la French Riviera.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#organization\",\"name\":\"Monaco Tribune\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo-monaco-tribune.png\",\"contentUrl\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo-monaco-tribune.png\",\"width\":1548,\"height\":600,\"caption\":\"Monaco Tribune\"},\"image\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MonacoTribune\",\"https:\\\/\\\/x.com\\\/MonacoTribune\",\"https:\\\/\\\/www.instagram.com\\\/monacotribune\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/monaco-tribune\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCHle1MnG6hw1y4lWKijVbMA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#\\\/schema\\\/person\\\/a855d420fff4d03637641d60b93ac62e\",\"name\":\"Camille Esteve\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eaaa2355a7bb56c0018a391c20a55bf9b4690e3f493231dd850e612bfa6ce161?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eaaa2355a7bb56c0018a391c20a55bf9b4690e3f493231dd850e612bfa6ce161?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eaaa2355a7bb56c0018a391c20a55bf9b4690e3f493231dd850e612bfa6ce161?s=96&d=mm&r=g\",\"caption\":\"Camille Esteve\"},\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/author\\\/camilleesteve\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Elizabeth Wessel: un ago in una mano, un pennello nell'altra","description":"Stilista e pittrice monegasca di origine danese, Elizabeth Wessel ha appena partecipato al Luxembourg Art Prize 2021. Un grande orgoglio. \u00c8 questo quello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.monaco-tribune.com\/it\/2021\/12\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\/","og_locale":"it_IT","og_type":"article","og_title":"Elizabeth Wessel: un ago in una mano, un pennello nell'altra - Monaco Tribune","og_description":"Stilista e pittrice monegasca di origine danese, Elizabeth Wessel ha appena partecipato al Luxembourg Art Prize 2021. Un grande orgoglio. \u00c8 questo quello","og_url":"https:\/\/www.monaco-tribune.com\/it\/2021\/12\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\/","og_site_name":"Monaco Tribune","article_publisher":"https:\/\/www.facebook.com\/MonacoTribune","article_published_time":"2021-12-24T11:19:13+00:00","article_modified_time":"2022-01-22T17:02:58+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2021\/12\/66-expo-ew-opera-gallery-hongkong.jpg","type":"image\/jpeg"}],"author":"Camille Esteve","twitter_card":"summary_large_image","twitter_creator":"@MonacoTribune","twitter_site":"@MonacoTribune","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.monaco-tribune.com\/it\/2021\/12\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\/#article","isPartOf":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2021\/12\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\/"},"author":{"name":"Camille Esteve","@id":"https:\/\/www.monaco-tribune.com\/it\/#\/schema\/person\/a855d420fff4d03637641d60b93ac62e"},"headline":"Elizabeth Wessel: un ago in una mano, un pennello nell&#8217;altra","datePublished":"2021-12-24T11:19:13+00:00","dateModified":"2022-01-22T17:02:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2021\/12\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\/"},"wordCount":564,"publisher":{"@id":"https:\/\/www.monaco-tribune.com\/it\/#organization"},"image":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2021\/12\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2021\/12\/66-expo-ew-opera-gallery-hongkong.jpg","articleSection":["Cosa fare","La nostra scelta","Notizie"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.monaco-tribune.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.monaco-tribune.com\/it\/2021\/12\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\/","url":"https:\/\/www.monaco-tribune.com\/it\/2021\/12\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\/","name":"Elizabeth Wessel: un ago in una mano, un pennello nell'altra","isPartOf":{"@id":"https:\/\/www.monaco-tribune.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2021\/12\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\/#primaryimage"},"image":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2021\/12\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2021\/12\/66-expo-ew-opera-gallery-hongkong.jpg","datePublished":"2021-12-24T11:19:13+00:00","dateModified":"2022-01-22T17:02:58+00:00","description":"Stilista e pittrice monegasca di origine danese, Elizabeth Wessel ha appena partecipato al Luxembourg Art Prize 2021. Un grande orgoglio. \u00c8 questo quello","breadcrumb":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2021\/12\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.monaco-tribune.com\/it\/2021\/12\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.monaco-tribune.com\/it\/2021\/12\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\/#primaryimage","url":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2021\/12\/66-expo-ew-opera-gallery-hongkong.jpg","contentUrl":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2021\/12\/66-expo-ew-opera-gallery-hongkong.jpg","width":1200,"height":800,"caption":"DR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.monaco-tribune.com\/it\/2021\/12\/elizabeth-wessel-un-ago-in-una-mano-un-pennello-nellaltra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.monaco-tribune.com\/it\/"},{"@type":"ListItem","position":2,"name":"Elizabeth Wessel: un ago in una mano, un pennello nell&rsquo;altra"}]},{"@type":"WebSite","@id":"https:\/\/www.monaco-tribune.com\/it\/#website","url":"https:\/\/www.monaco-tribune.com\/it\/","name":"Monaco Tribune","description":"Monaco : actualit\u00e9s \u00e9conomiques, politiques, culturelles et sportives de Monaco et de la French Riviera.","publisher":{"@id":"https:\/\/www.monaco-tribune.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.monaco-tribune.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.monaco-tribune.com\/it\/#organization","name":"Monaco Tribune","url":"https:\/\/www.monaco-tribune.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.monaco-tribune.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2022\/11\/logo-monaco-tribune.png","contentUrl":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2022\/11\/logo-monaco-tribune.png","width":1548,"height":600,"caption":"Monaco Tribune"},"image":{"@id":"https:\/\/www.monaco-tribune.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MonacoTribune","https:\/\/x.com\/MonacoTribune","https:\/\/www.instagram.com\/monacotribune\/","https:\/\/www.linkedin.com\/company\/monaco-tribune","https:\/\/www.youtube.com\/channel\/UCHle1MnG6hw1y4lWKijVbMA"]},{"@type":"Person","@id":"https:\/\/www.monaco-tribune.com\/it\/#\/schema\/person\/a855d420fff4d03637641d60b93ac62e","name":"Camille Esteve","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eaaa2355a7bb56c0018a391c20a55bf9b4690e3f493231dd850e612bfa6ce161?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eaaa2355a7bb56c0018a391c20a55bf9b4690e3f493231dd850e612bfa6ce161?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eaaa2355a7bb56c0018a391c20a55bf9b4690e3f493231dd850e612bfa6ce161?s=96&d=mm&r=g","caption":"Camille Esteve"},"url":"https:\/\/www.monaco-tribune.com\/it\/author\/camilleesteve\/"}]}},"_links":{"self":[{"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/posts\/104970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/comments?post=104970"}],"version-history":[{"count":0,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/posts\/104970\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/media\/104955"}],"wp:attachment":[{"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/media?parent=104970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/categories?post=104970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/tags?post=104970"},{"taxonomy":"sectag","embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/post_sectags?post=104970"},{"taxonomy":"format","embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/post_format?post=104970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}