{"id":248858,"date":"2024-09-06T17:24:12","date_gmt":"2024-09-06T15:24:12","guid":{"rendered":"https:\/\/www.monaco-tribune.com\/2024\/09\/un-rientro-a-scuola-allinsegna-dellinclusivita\/"},"modified":"2024-09-06T17:24:22","modified_gmt":"2024-09-06T15:24:22","slug":"un-rientro-a-scuola-allinsegna-dellinclusivita","status":"publish","type":"post","link":"https:\/\/www.monaco-tribune.com\/it\/2024\/09\/un-rientro-a-scuola-allinsegna-dellinclusivita\/","title":{"rendered":"Un rientro a scuola all&#8217;insegna dell&#8217;inclusivit\u00e0"},"content":{"rendered":"\n<p><strong>Nei loro interventi, Lionel Beffre e Jean-Philippe Vinci hanno entrambi sottolineato il modello inclusivo che intendono sviluppare nel Principato, per poi presentare il nuovo Coll\u00e8ge Charles III.<\/strong><\/p>\n\n<p>Inizia un nuovo anno scolastico anche per il personale docente. In occasione della tradizionale conferenza stampa sul rientro a scuola, il nuovo Consigliere di Governo e Ministro dell&#8217;Interno, Lionel Beffre, ha aperto la conferenza con un pizzico di umorismo: \u201cAnche per me \u00e8 il primo giorno di scuola&#8221;.<\/p>\n\n<p>Nel suo discorso inaugurale, Lionel Beffre ha sottolineato l&#8217;aspetto inclusivo dell&#8217;istruzione monegasca. Ha menzionato le classi speciali per i giovani sportivi e le disposizioni in vigore per gli alunni disabili. Per concludere, ha dichiarato che \u201cquesto nuovo anno scolastico \u00e8 stato preparato meticolosamente, con la volont\u00e0 di fare di tutto per garantire agli alunni un ambiente pi\u00f9 confortevole possibile e agli insegnanti il pi\u00f9 soddisfacente per esercitare le loro competenze didattiche\u201d.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-jean-philippe-vinci-l-ecole-ce-n-est-pas-seulement-apprendre-c-est-apprendre-ensemble\">Jean-Philippe Vinci, &#8220;La scuola non \u00e8 solo imparare, \u00e8 imparare insieme&#8221;.<\/h2>\n\n<p>Anche per Jean-Philippe Vinci questo \u00e8 un nuovo inizio, non pi\u00f9 come insegnante ma come nuovo Direttore dell&#8217;Istruzione Nazionale, della Giovent\u00f9 e dello Sport.<\/p>\n\n<p>Per i 5.694 studenti del Principato, Jean-Philippe Vinci intende mantenere \u201cuna certa continuit\u00e0\u201d con le politiche adottate dai suoi predecessori, perch\u00e9, a suo avviso, \u201cle politiche educative sono un processo a lungo termine\u201d. Ha sottolineato in diverse occasioni che la sua priorit\u00e0 \u00e8 incoraggiare \u201cla gioia di imparare\u201d.<\/p>\n\n<p>Ispirandosi alla massima di Philippe Meirieu secondo cui \u201cla scuola non \u00e8 solo imparare, ma imparare insieme\u201d, intende apprendere anche lui insieme agli altri, ma anche grazie agli altri, e afferma di avere gi\u00e0 \u201cdiversi progetti per il prossimo anno\u201d.<\/p>\n\n<p>Sostiene inoltre un approccio inclusivo: \u201cVivere insieme, imparare insieme e adattarsi\u201d, specificando che \u00e8 necessario \u201caccogliere e sostenere ogni alunno in modo individuale\u201d per costruire \u201cuna scuola accessibile a tutti dove ognuno trovi il suo posto\u201d. Sottolinea poi che non sono gli alunni con \u201cbisogni speciali a doversi adattare, ma \u00e8 l&#8217;intera classe a dover lavorare insieme\u201d.<\/p>\n\n<p class=\"related\"><a href=\"https:\/\/www.monaco-tribune.com\/it\/2024\/09\/chi-sono-i-nuovi-consiglieri-di-governo\/\">Chi sono i nuovi Consiglieri di Governo?<\/a><\/p>\n\n<p>La cultura, pilastro dell&#8217;istruzione monegasca, svolge un ruolo centrale, con 200 attivit\u00e0 culturali in programma quest&#8217;anno. Tra queste, 60 gite scolastiche, in parte finanziate dal Governo, e incontri con personalit\u00e0 come Hugo Duminil-Copin, matematico e vincitore della Medaglia Fields, Didier Queloz, astronomo e premio Nobel per la fisica, e Dja\u00efli Amadou Amal, scrittore e vincitore del Prix Goncourt des lyc\u00e9ens.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-le-numerique-en-usage-raisonne\">S\u00ec alla teconolgia, ma con parsimonia<\/h2>\n\n<p>Per quanto riguarda la tecnologia digitale, Jean-Philippe Vinci \u00e8 favorevole a un \u201cuso intelligente\u201d. Ritiene che spetti agli adulti rendere \u201cil reale pi\u00f9 interessante del virtuale\u201d e che la tecnologia debba essere utilizzata solo \u201cse offre qualcosa, altrimenti tanto vale tenersi carta e penna\u201d.<\/p>\n\n<p>Ci\u00f2 detto, la tecnologia ha comunque il suo posto nel nuovo Coll\u00e8ge Charles III, che dispone di 2.400 computer e segna un investimento significativo. Ogni aula \u00e8 dotata di un monitor digitale interattivo integrato nella lavagna.<\/p>\n\n<p>Malgrado non sia ancora previsto un divieto totale di utilizzo dei telefoni, l&#8217;uso degli smartphone \u00e8 comunque proibito.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-un-nouveau-college-flambant-neuf\">Un &#8220;coll\u00e8ge&#8221; nuovo di zecca<\/h2>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" src=\"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2024\/09\/piscine-college-charles-iii-1024x769.jpg\" alt=\"piscine-coll&#xE8;ge-charles-iii\" class=\"wp-image-248787\" srcset=\"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2024\/09\/piscine-college-charles-iii-1024x769.jpg 1024w, https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2024\/09\/piscine-college-charles-iii-400x300.jpg 400w, https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2024\/09\/piscine-college-charles-iii.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>La nuova piscina dovrebbe sostituire quella dell&#8217;Annonciade \u00a9 Monaco Tribune \/ Th\u00e9o Briand<\/em><\/figcaption><\/figure>\n<\/div>\n<p>Questo nuovo anno scolastico segna anche l&#8217;apertura di un nuovissimo Coll\u00e8ge Charles III, molto pi\u00f9 spazioso del vecchio edificio di avenue de l&#8217;Annonciade. Con una superficie di 23.805 m\u00b2 e 12 piani, la scuola dispone di strutture moderne e di una variet\u00e0 di spazi che adesso consentono agli studenti di svolgere le loro attivit\u00e0 senza uscire dalla scuola.<\/p>\n\n<p>Ecco un piccolo assaggio dell&#8217;incredibile offerta del Coll\u00e8ge Charles III: quattro parchi giochi, due al piano terra per la 6\u1d43 e la 5\u1d43, e altri due in cima all&#8217;edificio, al 7\u00b0 piano, per la 4\u1d43 e la 3\u1d43; una mensa da 400 posti; una piscina lunga 25 metri e larga 20 metri; una palestra di 1.000 m\u00b2, una biblioteca e un anfiteatro da 270 posti, ciascuno dotato di un tablet e di una presa di corrente.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" src=\"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2024\/09\/cour-sommet-college-charles-iii-1024x769.jpg\" alt=\"cour-sommet-college-charles-iii\" class=\"wp-image-248779\" srcset=\"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2024\/09\/cour-sommet-college-charles-iii-1024x769.jpg 1024w, https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2024\/09\/cour-sommet-college-charles-iii-400x300.jpg 400w, https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2024\/09\/cour-sommet-college-charles-iii.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Il cortile delle classi 4\u00aa e 3\u00aa offre una vista mozzafiato sul Palazzo del Principe e sul quartiere di Fontvieille \u00a9 Monaco Tribune \/ Th\u00e9o Briand<\/em><\/figcaption><\/figure>\n<\/div><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" src=\"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2024\/09\/self-college-charles-iii-1024x769.jpg\" alt=\"self-college-charles-iii\" class=\"wp-image-248783\" srcset=\"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2024\/09\/self-college-charles-iii-1024x769.jpg 1024w, https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2024\/09\/self-college-charles-iii-400x300.jpg 400w, https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2024\/09\/self-college-charles-iii.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Il Self-service \u00e8 a volont\u00e0 \u00a9 Monaco Tribune \/ Th\u00e9o Briand<\/em><\/figcaption><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Nei loro interventi, Lionel Beffre e Jean-Philippe Vinci hanno entrambi sottolineato il modello inclusivo che intendono sviluppare nel Principato, per [&hellip;]<\/p>\n","protected":false},"author":66,"featured_media":248777,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1738,1752],"tags":[3220],"post_sectags":[5107],"post_format":[2478],"class_list":["post-248858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie","category-societa","tag-politica","sectag-college-charles-iii-it","format-notizia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Un rientro a scuola all&#039;insegna dell&#039;inclusivit\u00e0<\/title>\n<meta name=\"description\" content=\"Nei loro interventi, Lionel Beffre e Jean-Philippe Vinci hanno entrambi sottolineato il modello inclusivo che intendono sviluppare nel Principato, per poi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.monaco-tribune.com\/it\/2024\/09\/un-rientro-a-scuola-allinsegna-dellinclusivita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un rientro a scuola all&#039;insegna dell&#039;inclusivit\u00e0 - Monaco Tribune\" \/>\n<meta property=\"og:description\" content=\"Nei loro interventi, Lionel Beffre e Jean-Philippe Vinci hanno entrambi sottolineato il modello inclusivo che intendono sviluppare nel Principato, per poi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.monaco-tribune.com\/it\/2024\/09\/un-rientro-a-scuola-allinsegna-dellinclusivita\/\" \/>\n<meta property=\"og:site_name\" content=\"Monaco Tribune\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MonacoTribune\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-06T15:24:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-06T15:24:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2024\/09\/conference-rentree-scolaire-lionel-beffre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Th\u00e9o Briand\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MonacoTribune\" \/>\n<meta name=\"twitter:site\" content=\"@MonacoTribune\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2024\\\/09\\\/un-rientro-a-scuola-allinsegna-dellinclusivita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2024\\\/09\\\/un-rientro-a-scuola-allinsegna-dellinclusivita\\\/\"},\"author\":{\"name\":\"Th\u00e9o Briand\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#\\\/schema\\\/person\\\/94fb5723547bd83dea1eed97e25145aa\"},\"headline\":\"Un rientro a scuola all&#8217;insegna dell&#8217;inclusivit\u00e0\",\"datePublished\":\"2024-09-06T15:24:12+00:00\",\"dateModified\":\"2024-09-06T15:24:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2024\\\/09\\\/un-rientro-a-scuola-allinsegna-dellinclusivita\\\/\"},\"wordCount\":680,\"publisher\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2024\\\/09\\\/un-rientro-a-scuola-allinsegna-dellinclusivita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/conference-rentree-scolaire-lionel-beffre.jpg\",\"keywords\":[\"Politica\"],\"articleSection\":[\"Notizie\",\"Societ\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2024\\\/09\\\/un-rientro-a-scuola-allinsegna-dellinclusivita\\\/\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2024\\\/09\\\/un-rientro-a-scuola-allinsegna-dellinclusivita\\\/\",\"name\":\"Un rientro a scuola all'insegna dell'inclusivit\u00e0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2024\\\/09\\\/un-rientro-a-scuola-allinsegna-dellinclusivita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2024\\\/09\\\/un-rientro-a-scuola-allinsegna-dellinclusivita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/conference-rentree-scolaire-lionel-beffre.jpg\",\"datePublished\":\"2024-09-06T15:24:12+00:00\",\"dateModified\":\"2024-09-06T15:24:22+00:00\",\"description\":\"Nei loro interventi, Lionel Beffre e Jean-Philippe Vinci hanno entrambi sottolineato il modello inclusivo che intendono sviluppare nel Principato, per poi\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2024\\\/09\\\/un-rientro-a-scuola-allinsegna-dellinclusivita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2024\\\/09\\\/un-rientro-a-scuola-allinsegna-dellinclusivita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2024\\\/09\\\/un-rientro-a-scuola-allinsegna-dellinclusivita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/conference-rentree-scolaire-lionel-beffre.jpg\",\"contentUrl\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/conference-rentree-scolaire-lionel-beffre.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Lionel Beffre, Consigliere di Governo e Ministro dell'Interno, e Jean-Philippe Vinci, Direttore dell'Istruzione Nazionale, della Giovent\u00f9 e dello Sport, hanno preso la parola \u00a9 Monaco Tribune \\\/ Th\u00e9o Briand\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2024\\\/09\\\/un-rientro-a-scuola-allinsegna-dellinclusivita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un rientro a scuola all&#8217;insegna dell&#8217;inclusivit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/\",\"name\":\"Monaco Tribune\",\"description\":\"Monaco : actualit\u00e9s \u00e9conomiques, politiques, culturelles et sportives de Monaco et de la French Riviera.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#organization\",\"name\":\"Monaco Tribune\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo-monaco-tribune.png\",\"contentUrl\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo-monaco-tribune.png\",\"width\":1548,\"height\":600,\"caption\":\"Monaco Tribune\"},\"image\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MonacoTribune\",\"https:\\\/\\\/x.com\\\/MonacoTribune\",\"https:\\\/\\\/www.instagram.com\\\/monacotribune\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/monaco-tribune\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCHle1MnG6hw1y4lWKijVbMA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#\\\/schema\\\/person\\\/94fb5723547bd83dea1eed97e25145aa\",\"name\":\"Th\u00e9o Briand\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c02cfd8b8054d8c376f9a942a1dc4dbacfd8ba5e6f8dbb5e16f4aa3d281972a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c02cfd8b8054d8c376f9a942a1dc4dbacfd8ba5e6f8dbb5e16f4aa3d281972a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c02cfd8b8054d8c376f9a942a1dc4dbacfd8ba5e6f8dbb5e16f4aa3d281972a?s=96&d=mm&r=g\",\"caption\":\"Th\u00e9o Briand\"},\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/author\\\/theobriand\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un rientro a scuola all'insegna dell'inclusivit\u00e0","description":"Nei loro interventi, Lionel Beffre e Jean-Philippe Vinci hanno entrambi sottolineato il modello inclusivo che intendono sviluppare nel Principato, per poi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.monaco-tribune.com\/it\/2024\/09\/un-rientro-a-scuola-allinsegna-dellinclusivita\/","og_locale":"it_IT","og_type":"article","og_title":"Un rientro a scuola all'insegna dell'inclusivit\u00e0 - Monaco Tribune","og_description":"Nei loro interventi, Lionel Beffre e Jean-Philippe Vinci hanno entrambi sottolineato il modello inclusivo che intendono sviluppare nel Principato, per poi","og_url":"https:\/\/www.monaco-tribune.com\/it\/2024\/09\/un-rientro-a-scuola-allinsegna-dellinclusivita\/","og_site_name":"Monaco Tribune","article_publisher":"https:\/\/www.facebook.com\/MonacoTribune","article_published_time":"2024-09-06T15:24:12+00:00","article_modified_time":"2024-09-06T15:24:22+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2024\/09\/conference-rentree-scolaire-lionel-beffre.jpg","type":"image\/jpeg"}],"author":"Th\u00e9o Briand","twitter_card":"summary_large_image","twitter_creator":"@MonacoTribune","twitter_site":"@MonacoTribune","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.monaco-tribune.com\/it\/2024\/09\/un-rientro-a-scuola-allinsegna-dellinclusivita\/#article","isPartOf":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2024\/09\/un-rientro-a-scuola-allinsegna-dellinclusivita\/"},"author":{"name":"Th\u00e9o Briand","@id":"https:\/\/www.monaco-tribune.com\/it\/#\/schema\/person\/94fb5723547bd83dea1eed97e25145aa"},"headline":"Un rientro a scuola all&#8217;insegna dell&#8217;inclusivit\u00e0","datePublished":"2024-09-06T15:24:12+00:00","dateModified":"2024-09-06T15:24:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2024\/09\/un-rientro-a-scuola-allinsegna-dellinclusivita\/"},"wordCount":680,"publisher":{"@id":"https:\/\/www.monaco-tribune.com\/it\/#organization"},"image":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2024\/09\/un-rientro-a-scuola-allinsegna-dellinclusivita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2024\/09\/conference-rentree-scolaire-lionel-beffre.jpg","keywords":["Politica"],"articleSection":["Notizie","Societ\u00e0"],"inLanguage":"it-IT","copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.monaco-tribune.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.monaco-tribune.com\/it\/2024\/09\/un-rientro-a-scuola-allinsegna-dellinclusivita\/","url":"https:\/\/www.monaco-tribune.com\/it\/2024\/09\/un-rientro-a-scuola-allinsegna-dellinclusivita\/","name":"Un rientro a scuola all'insegna dell'inclusivit\u00e0","isPartOf":{"@id":"https:\/\/www.monaco-tribune.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2024\/09\/un-rientro-a-scuola-allinsegna-dellinclusivita\/#primaryimage"},"image":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2024\/09\/un-rientro-a-scuola-allinsegna-dellinclusivita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2024\/09\/conference-rentree-scolaire-lionel-beffre.jpg","datePublished":"2024-09-06T15:24:12+00:00","dateModified":"2024-09-06T15:24:22+00:00","description":"Nei loro interventi, Lionel Beffre e Jean-Philippe Vinci hanno entrambi sottolineato il modello inclusivo che intendono sviluppare nel Principato, per poi","breadcrumb":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2024\/09\/un-rientro-a-scuola-allinsegna-dellinclusivita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.monaco-tribune.com\/it\/2024\/09\/un-rientro-a-scuola-allinsegna-dellinclusivita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.monaco-tribune.com\/it\/2024\/09\/un-rientro-a-scuola-allinsegna-dellinclusivita\/#primaryimage","url":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2024\/09\/conference-rentree-scolaire-lionel-beffre.jpg","contentUrl":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2024\/09\/conference-rentree-scolaire-lionel-beffre.jpg","width":1200,"height":800,"caption":"Lionel Beffre, Consigliere di Governo e Ministro dell'Interno, e Jean-Philippe Vinci, Direttore dell'Istruzione Nazionale, della Giovent\u00f9 e dello Sport, hanno preso la parola \u00a9 Monaco Tribune \/ Th\u00e9o Briand"},{"@type":"BreadcrumbList","@id":"https:\/\/www.monaco-tribune.com\/it\/2024\/09\/un-rientro-a-scuola-allinsegna-dellinclusivita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.monaco-tribune.com\/it\/"},{"@type":"ListItem","position":2,"name":"Un rientro a scuola all&#8217;insegna dell&#8217;inclusivit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/www.monaco-tribune.com\/it\/#website","url":"https:\/\/www.monaco-tribune.com\/it\/","name":"Monaco Tribune","description":"Monaco : actualit\u00e9s \u00e9conomiques, politiques, culturelles et sportives de Monaco et de la French Riviera.","publisher":{"@id":"https:\/\/www.monaco-tribune.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.monaco-tribune.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.monaco-tribune.com\/it\/#organization","name":"Monaco Tribune","url":"https:\/\/www.monaco-tribune.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.monaco-tribune.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2022\/11\/logo-monaco-tribune.png","contentUrl":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2022\/11\/logo-monaco-tribune.png","width":1548,"height":600,"caption":"Monaco Tribune"},"image":{"@id":"https:\/\/www.monaco-tribune.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MonacoTribune","https:\/\/x.com\/MonacoTribune","https:\/\/www.instagram.com\/monacotribune\/","https:\/\/www.linkedin.com\/company\/monaco-tribune","https:\/\/www.youtube.com\/channel\/UCHle1MnG6hw1y4lWKijVbMA"]},{"@type":"Person","@id":"https:\/\/www.monaco-tribune.com\/it\/#\/schema\/person\/94fb5723547bd83dea1eed97e25145aa","name":"Th\u00e9o Briand","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1c02cfd8b8054d8c376f9a942a1dc4dbacfd8ba5e6f8dbb5e16f4aa3d281972a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1c02cfd8b8054d8c376f9a942a1dc4dbacfd8ba5e6f8dbb5e16f4aa3d281972a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1c02cfd8b8054d8c376f9a942a1dc4dbacfd8ba5e6f8dbb5e16f4aa3d281972a?s=96&d=mm&r=g","caption":"Th\u00e9o Briand"},"url":"https:\/\/www.monaco-tribune.com\/it\/author\/theobriand\/"}]}},"_links":{"self":[{"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/posts\/248858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/comments?post=248858"}],"version-history":[{"count":2,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/posts\/248858\/revisions"}],"predecessor-version":[{"id":248861,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/posts\/248858\/revisions\/248861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/media\/248777"}],"wp:attachment":[{"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/media?parent=248858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/categories?post=248858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/tags?post=248858"},{"taxonomy":"sectag","embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/post_sectags?post=248858"},{"taxonomy":"format","embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/post_format?post=248858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}