{"id":28229,"date":"2020-05-25T17:51:42","date_gmt":"2020-05-25T15:51:42","guid":{"rendered":"https:\/\/www.monaco-tribune.com\/2020\/05\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\/"},"modified":"2020-07-23T11:48:54","modified_gmt":"2020-07-23T09:48:54","slug":"denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza","status":"publish","type":"post","link":"https:\/\/www.monaco-tribune.com\/it\/2020\/05\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\/","title":{"rendered":"Denis Allemand (CSM): &#8220;Questa crisi sanitaria metter\u00e0 in risalto l\u2019interesse delle persone per la scienza&#8221;"},"content":{"rendered":"<p><strong>Spesso trascurata, spesso dimenticata, la scienza \u00e8 di nuovo al centro delle nostre preoccupazioni in piena crisi sanitaria. Direttore scientifico del CMS, il professor Denis Allemand si \u00e8 preso la briga di raccontarsi a Monaco Tribune.<\/strong><\/p>\n<p>Centro di ricerca del Principato dalla sua istituzione nel 1960 per opera del principe Rainier III, il <a href=\"https:\/\/www.centrescientifique.mc\/fr\">Centro Scientifico di Monaco<\/a> \u00e8 il centro di ricerca del Principato. Particolarmente attivo durante l\u2019anno e in particolare in questo periodo di crisi sanitaria, il CSM \u00e8 uno dei polmoni di Monaco. Il suo direttore scientifico, <a href=\"https:\/\/www.centrescientifique.mc\/fr\/annuaire-scientifique\/fiche\/denis-allemand\">Denis Allemand<\/a> si \u00e8 espresso per parlare della situazione attuale e del ruolo di un centro a cui non viene data la giusta attenzione, e la professione di scienziato, a volte non riconosciuta a sufficienza.<\/p>\n<p><strong>Denis, lei pensa che la crisi sanitaria ed economica legata al coronavirus spinger\u00e0 le persone a interessarsi maggiormente allo sviluppo sostenibile e alle problematiche scientifiche?<\/strong><\/p>\n<p>Questa crisi sanitaria unica nel suo genere metter\u00e0 in risalto l\u2019interesse delle persone per la scienza. \u00c8 una certezza. Ci sono ricadute positive di questa crisi catastrofica. Durante la quarantena, c\u2019\u00e8 stato un forte interesse del pubblico per le pubblicazioni scientifiche, per leggere articoli che non avrebbero mai aperto alcune settimane fa. Questo dimostra che quando c\u2019\u00e8 un problema, tutti si rivolgono ai ricercatori per avere delle spiegazioni e risposte, poich\u00e9 detengono una parte della conoscenza o sono in ogni caso all\u2019origine di questa conoscenza.<\/p>\n<blockquote><p>Finora, la ricerca non \u00e8 mai stata la priorit\u00e0 di molti stati<\/p><\/blockquote>\n<p><strong>Finora ha ritenuto che ci fosse meno interesse per la scienza?<\/strong><\/p>\n<p>\u00c8 vero che quando vediamo le notizie, la scienza, gli ultimi dati della ricerca, fanno raramente notizia a meno che qualcosa non sconvolga le conoscenze, mentre la scienza si scopre man mano per costruire questo grande edificio della ricerca e della conoscenza. Finora, la ricerca non \u00e8 mai stata la priorit\u00e0 di molti stati.<\/p>\n<p><strong>In Francia, l\u2019unico test affidabile consigliato per lo screening del coronavirus \u00e8 il test sierologico attraverso PCR. Pu\u00f2 parlarci delle origini di questo processo?<\/strong><\/p>\n<p>Come ho gi\u00e0 affermato precedentemente, la scienza si basa su piccoli risultati e attualmente si parla molto sui giornali della PCR (tecnica di amplificazione enzimatica che permette di ottenere un elevato numero di copie identiche a partire da un frammento di DNA), una tecnica basata sulla scoperta da parte di un ricercatore negli anni \u201960 di un batterio che viveva nei laghi del Parco Nazionale di Yellowstone, negli Stati Uniti. Una ricerca sulla biodiversit\u00e0 microbiologica di questi laghi acidi e caldi, che non aveva alcuno scopo medico. Questo ricercatore ha descritto un batterio che pu\u00f2 vivere fino a 85\u00b0, e in seguito altri ricercatori lo hanno studiato pi\u00f9 dettagliatamente, isolando da questo batterio alcuni enzimi che possono funzionare ad alte temperature ed \u00e8 nata l\u2019idea di utilizzarlo per amplificare il DNA, una tecnica che stava emergendo proprio allora. Quest\u2019ultimi hanno inoltre ottenuto per questa scoperta il Premio Nobel per la chimica. Cos\u00ec oggi, se siamo in grado di identificare il virus, se la PCR \u00e8 utilizzata in tutti i laboratori e all\u2019interno delle forze di polizia scientifica, \u00e8 grazie ad una semplice scoperta di un microbiologo che stava studiando la biodiversit\u00e0. Se non fosse stato per questa ricerca e per questa diagnosi cos\u00ec precisa, non saremmo a questo punto. \u00c8 importante cercare, senza tuttavia cercare un utilizzo. \u00c8 la ricerca che porter\u00e0 agli utilizzi e non il contrario.<\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CAjuG1FFE69\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"12\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">View this post on Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/CAjuG1FFE69\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener noreferrer\">A post shared by Centre Scientifique De Monaco (@csm_monaco)<\/a> on <time style=\"font-family: Arial,sans-serif; font-size: 14px; line-height: 17px;\" datetime=\"2020-05-24T05:01:46+00:00\">May 23, 2020 at 10:01pm PDT<\/time><\/p>\n<\/div>\n<\/blockquote>\n<p><script async=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p><strong>All\u2019interno del Centro Scientifico di Monaco, quali sono le principali missioni e ricerche effettuate?<\/strong><\/p>\n<p>Il nostro ruolo principale \u00e8 lo sviluppo della ricerca e della conoscenza nelle diverse accezioni, in particolare nel legame con gli ospedali, al fine di migliorare le cure per alcune patologie. Abbiamo anche la ricerca applicata che ha permesso il deposito di diversi brevetti. Uno di questi \u00e8 stato appena sviluppato nell\u2019ambito di una startup all\u2019interno di MonacoTech, Carliotech, sviluppata da un ex ricercatore del CSM, sulla base di un brevetto depositato dal centro. Abbiamo anche una missione di competenza. Il CSM \u00e8 in grado di finanziare programmi di ricerca clinici. Lo Stato ci ha chiesto, ad esempio, di sviluppare programmi di ricerca clinici per stimolare questa ricerca nel Principato. La ricerca clinica \u00e8 finanziata in Francia dai Centri ospedalieri universitari, ma questi ultimi non esistono a Monaco. I medici del Principato propongono quindi dei progetti al CSM che sono valutati da un gruppo di esperti. Noi abbiamo anche un compito di formazione, con pi\u00f9 di trenta dottorandi formati al CSM. E per concludere, parler\u00f2 di una missione per promuovere la scienza. Il centro organizza conferenze per il pubblico, pubblica articoli su giornali, in stretta collaborazione con l\u2019associazione degli \u201cAmici del CSM\u201d, avviato dagli appassionati della scienza per aiutare il centro nelle sue principali missioni. Ma la crisi del Covid-19 l\u2019ha dimostrato, un centro di ricerca come il CSM \u00e8 in grado di essere reattivo e di proporre, alle autorit\u00e0 sanitarie del Principato, sia di mettere le proprie attrezzature scientifiche al servizio dei test sia di offrire miglioramenti alle stesse.<\/p>\n<p><strong>Quali sono le principali aree di competenza del CSM?<\/strong><\/p>\n<p>La prima, storica, che portiamo avanti da trent\u2019anni, riguarda lo studio degli ecosistemi corallini, nel Mediterraneo, preziosi coralli rossi e coralli d\u2019acqua fredda, ma anche coralli tropicali delle scogliere. Possediamo le pi\u00f9 antiche colture di corallo controllate al mondo da oltre trent\u2019anni. La seconda area di competenza riguarda la biologia polare, con lo studio dei pinguini, usati come indicatori dello stato di salute di questi ecosistemi. Questo ambito \u00e8 stato iniziato durante il viaggio in Antartide del Principe Sovrano, che voleva che il CSM fosse associato a questo viaggio. Da allora questa attivit\u00e0 scientifica \u00e8 stata portata avanti. Infine, da quando il centro si \u00e8 trasferito a Quai Antoine I, abbiamo istituito un terzo settore che studia la biologia medica, ripartita in quattro grandi ambiti. La ricerca contro il cancro pediatrico, in collaborazione con l\u2019associazione Flavien di Denis Maccario; una ricerca contro le patologie muscolari, in collaborazione con l\u2019associazione monegasca contro le Miopatie, e infine una ricerca sul microbiota intestinale e il suo controllo da parte del sistema immunitario o da parte dei probiotici e una ricerca epidemica sull\u2019anemia falciforme. Infine abbiamo un\u2019Unit\u00e0 di salute umana e ambiente che si concentra, tra l\u2019altro, sui legami tra cambiamento climatico e salute umana, in particolare negli Oceani.<\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CAelFKvDwQ4\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"12\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">View this post on Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/CAelFKvDwQ4\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener noreferrer\">A post shared by Centre Scientifique De Monaco (@csm_monaco)<\/a> on <time style=\"font-family: Arial,sans-serif; font-size: 14px; line-height: 17px;\" datetime=\"2020-05-22T05:06:42+00:00\">May 21, 2020 at 10:06pm PDT<\/time><\/p>\n<\/div>\n<\/blockquote>\n<p><script async=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Spesso trascurata, spesso dimenticata, la scienza \u00e8 di nuovo al centro delle nostre preoccupazioni in piena crisi sanitaria. Direttore scientifico [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":28217,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1738,1752],"tags":[2886],"post_sectags":[],"post_format":[2476],"class_list":["post-28229","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie","category-societa","tag-covid-19-it","format-intervista"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Denis Allemand (CSM): &quot;Questa crisi sanitaria metter\u00e0 in risalto l\u2019interesse delle persone per la scienza&quot;<\/title>\n<meta name=\"description\" content=\"Spesso trascurata, spesso dimenticata, la scienza \u00e8 di nuovo al centro delle nostre preoccupazioni in piena crisi sanitaria. Direttore scientifico del\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.monaco-tribune.com\/it\/2020\/05\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Denis Allemand (CSM): &quot;Questa crisi sanitaria metter\u00e0 in risalto l\u2019interesse delle persone per la scienza&quot; - Monaco Tribune\" \/>\n<meta property=\"og:description\" content=\"Spesso trascurata, spesso dimenticata, la scienza \u00e8 di nuovo al centro delle nostre preoccupazioni in piena crisi sanitaria. Direttore scientifico del\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.monaco-tribune.com\/it\/2020\/05\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\/\" \/>\n<meta property=\"og:site_name\" content=\"Monaco Tribune\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MonacoTribune\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-25T15:51:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-23T09:48:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2020\/05\/denis-allemand-centre-scientifique-de-monaco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1181\" \/>\n\t<meta property=\"og:image:height\" content=\"865\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Romain Boisaubert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MonacoTribune\" \/>\n<meta name=\"twitter:site\" content=\"@MonacoTribune\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/05\\\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/05\\\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\\\/\"},\"author\":{\"name\":\"Romain Boisaubert\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#\\\/schema\\\/person\\\/330a3732947cf8cb41b2533a0eadd62e\"},\"headline\":\"Denis Allemand (CSM): &#8220;Questa crisi sanitaria metter\u00e0 in risalto l\u2019interesse delle persone per la scienza&#8221;\",\"datePublished\":\"2020-05-25T15:51:42+00:00\",\"dateModified\":\"2020-07-23T09:48:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/05\\\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\\\/\"},\"wordCount\":1095,\"publisher\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/05\\\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/denis-allemand-centre-scientifique-de-monaco.jpg\",\"keywords\":[\"Covid-19\"],\"articleSection\":[\"Notizie\",\"Societ\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/05\\\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\\\/\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/05\\\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\\\/\",\"name\":\"Denis Allemand (CSM): \\\"Questa crisi sanitaria metter\u00e0 in risalto l\u2019interesse delle persone per la scienza\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/05\\\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/05\\\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/denis-allemand-centre-scientifique-de-monaco.jpg\",\"datePublished\":\"2020-05-25T15:51:42+00:00\",\"dateModified\":\"2020-07-23T09:48:54+00:00\",\"description\":\"Spesso trascurata, spesso dimenticata, la scienza \u00e8 di nuovo al centro delle nostre preoccupazioni in piena crisi sanitaria. Direttore scientifico del\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/05\\\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/05\\\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/05\\\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/denis-allemand-centre-scientifique-de-monaco.jpg\",\"contentUrl\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/denis-allemand-centre-scientifique-de-monaco.jpg\",\"width\":1181,\"height\":865,\"caption\":\"Centro scientifico di Monaco\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/05\\\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Denis Allemand (CSM): \u00ab\u00a0Questa crisi sanitaria metter\u00e0 in risalto l\u2019interesse delle persone per la scienza\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/\",\"name\":\"Monaco Tribune\",\"description\":\"Monaco : actualit\u00e9s \u00e9conomiques, politiques, culturelles et sportives de Monaco et de la French Riviera.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#organization\",\"name\":\"Monaco Tribune\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo-monaco-tribune.png\",\"contentUrl\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo-monaco-tribune.png\",\"width\":1548,\"height\":600,\"caption\":\"Monaco Tribune\"},\"image\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MonacoTribune\",\"https:\\\/\\\/x.com\\\/MonacoTribune\",\"https:\\\/\\\/www.instagram.com\\\/monacotribune\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/monaco-tribune\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCHle1MnG6hw1y4lWKijVbMA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#\\\/schema\\\/person\\\/330a3732947cf8cb41b2533a0eadd62e\",\"name\":\"Romain Boisaubert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8b90d41f1eabd1cbe4cf59e09d8db41a697d51919bf2dfe727589a24a4a4d54?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8b90d41f1eabd1cbe4cf59e09d8db41a697d51919bf2dfe727589a24a4a4d54?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8b90d41f1eabd1cbe4cf59e09d8db41a697d51919bf2dfe727589a24a4a4d54?s=96&d=mm&r=g\",\"caption\":\"Romain Boisaubert\"},\"description\":\"Test bio\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/author\\\/romain-boisaubert\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Denis Allemand (CSM): \"Questa crisi sanitaria metter\u00e0 in risalto l\u2019interesse delle persone per la scienza\"","description":"Spesso trascurata, spesso dimenticata, la scienza \u00e8 di nuovo al centro delle nostre preoccupazioni in piena crisi sanitaria. Direttore scientifico del","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.monaco-tribune.com\/it\/2020\/05\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\/","og_locale":"it_IT","og_type":"article","og_title":"Denis Allemand (CSM): \"Questa crisi sanitaria metter\u00e0 in risalto l\u2019interesse delle persone per la scienza\" - Monaco Tribune","og_description":"Spesso trascurata, spesso dimenticata, la scienza \u00e8 di nuovo al centro delle nostre preoccupazioni in piena crisi sanitaria. Direttore scientifico del","og_url":"https:\/\/www.monaco-tribune.com\/it\/2020\/05\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\/","og_site_name":"Monaco Tribune","article_publisher":"https:\/\/www.facebook.com\/MonacoTribune","article_published_time":"2020-05-25T15:51:42+00:00","article_modified_time":"2020-07-23T09:48:54+00:00","og_image":[{"width":1181,"height":865,"url":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2020\/05\/denis-allemand-centre-scientifique-de-monaco.jpg","type":"image\/jpeg"}],"author":"Romain Boisaubert","twitter_card":"summary_large_image","twitter_creator":"@MonacoTribune","twitter_site":"@MonacoTribune","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/05\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\/#article","isPartOf":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/05\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\/"},"author":{"name":"Romain Boisaubert","@id":"https:\/\/www.monaco-tribune.com\/it\/#\/schema\/person\/330a3732947cf8cb41b2533a0eadd62e"},"headline":"Denis Allemand (CSM): &#8220;Questa crisi sanitaria metter\u00e0 in risalto l\u2019interesse delle persone per la scienza&#8221;","datePublished":"2020-05-25T15:51:42+00:00","dateModified":"2020-07-23T09:48:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/05\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\/"},"wordCount":1095,"publisher":{"@id":"https:\/\/www.monaco-tribune.com\/it\/#organization"},"image":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/05\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2020\/05\/denis-allemand-centre-scientifique-de-monaco.jpg","keywords":["Covid-19"],"articleSection":["Notizie","Societ\u00e0"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.monaco-tribune.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/05\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\/","url":"https:\/\/www.monaco-tribune.com\/it\/2020\/05\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\/","name":"Denis Allemand (CSM): \"Questa crisi sanitaria metter\u00e0 in risalto l\u2019interesse delle persone per la scienza\"","isPartOf":{"@id":"https:\/\/www.monaco-tribune.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/05\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\/#primaryimage"},"image":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/05\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2020\/05\/denis-allemand-centre-scientifique-de-monaco.jpg","datePublished":"2020-05-25T15:51:42+00:00","dateModified":"2020-07-23T09:48:54+00:00","description":"Spesso trascurata, spesso dimenticata, la scienza \u00e8 di nuovo al centro delle nostre preoccupazioni in piena crisi sanitaria. Direttore scientifico del","breadcrumb":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/05\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.monaco-tribune.com\/it\/2020\/05\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/05\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\/#primaryimage","url":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2020\/05\/denis-allemand-centre-scientifique-de-monaco.jpg","contentUrl":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2020\/05\/denis-allemand-centre-scientifique-de-monaco.jpg","width":1181,"height":865,"caption":"Centro scientifico di Monaco"},{"@type":"BreadcrumbList","@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/05\/denis-allemand-centro-scientifico-di-monaco-questa-crisi-sanitaria-mettera-in-risalto-linteresse-delle-persone-per-la-scienza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.monaco-tribune.com\/it\/"},{"@type":"ListItem","position":2,"name":"Denis Allemand (CSM): \u00ab\u00a0Questa crisi sanitaria metter\u00e0 in risalto l\u2019interesse delle persone per la scienza\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.monaco-tribune.com\/it\/#website","url":"https:\/\/www.monaco-tribune.com\/it\/","name":"Monaco Tribune","description":"Monaco : actualit\u00e9s \u00e9conomiques, politiques, culturelles et sportives de Monaco et de la French Riviera.","publisher":{"@id":"https:\/\/www.monaco-tribune.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.monaco-tribune.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.monaco-tribune.com\/it\/#organization","name":"Monaco Tribune","url":"https:\/\/www.monaco-tribune.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.monaco-tribune.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2022\/11\/logo-monaco-tribune.png","contentUrl":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2022\/11\/logo-monaco-tribune.png","width":1548,"height":600,"caption":"Monaco Tribune"},"image":{"@id":"https:\/\/www.monaco-tribune.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MonacoTribune","https:\/\/x.com\/MonacoTribune","https:\/\/www.instagram.com\/monacotribune\/","https:\/\/www.linkedin.com\/company\/monaco-tribune","https:\/\/www.youtube.com\/channel\/UCHle1MnG6hw1y4lWKijVbMA"]},{"@type":"Person","@id":"https:\/\/www.monaco-tribune.com\/it\/#\/schema\/person\/330a3732947cf8cb41b2533a0eadd62e","name":"Romain Boisaubert","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f8b90d41f1eabd1cbe4cf59e09d8db41a697d51919bf2dfe727589a24a4a4d54?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f8b90d41f1eabd1cbe4cf59e09d8db41a697d51919bf2dfe727589a24a4a4d54?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f8b90d41f1eabd1cbe4cf59e09d8db41a697d51919bf2dfe727589a24a4a4d54?s=96&d=mm&r=g","caption":"Romain Boisaubert"},"description":"Test bio","url":"https:\/\/www.monaco-tribune.com\/it\/author\/romain-boisaubert\/"}]}},"_links":{"self":[{"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/posts\/28229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/comments?post=28229"}],"version-history":[{"count":0,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/posts\/28229\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/media\/28217"}],"wp:attachment":[{"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/media?parent=28229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/categories?post=28229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/tags?post=28229"},{"taxonomy":"sectag","embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/post_sectags?post=28229"},{"taxonomy":"format","embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/post_format?post=28229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}