{"id":58131,"date":"2020-12-14T11:36:56","date_gmt":"2020-12-14T10:36:56","guid":{"rendered":"https:\/\/www.monaco-tribune.com\/2020\/12\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\/"},"modified":"2020-12-14T11:40:08","modified_gmt":"2020-12-14T10:40:08","slug":"gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione","status":"publish","type":"post","link":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\/","title":{"rendered":"Gran Premio di Abu Dhabi: Charles Leclerc termina in tredicesima posizione"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Con la finale di Abu Dhabi della scorsa domenica, si \u00e8 concluso il Gran Premio del 2020. Il pilota Ferrari termina in tredicesima posizione, Max Verstappen (Red Bull) conquista il primo posto, seguito da Valtteri Bottas (Mercedes) e Lewis Hamilton (Mercedes).<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Siamo giunti alla fine e Charles Leclerc non sembra particolarmente dispiaciuto. Visibilmente provato da una stagione frustrante dal punto di vista delle prestazioni, il pilota monegasco confessa: &#8220;Mi \u00e8 dispiaciuto finire in questo modo. \u00c8 stata una stagione complicata e sono contento che sia finita&#8221;.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-une-course-difficile\">Una corsa difficile<\/h2>\n\n<p class=\"wp-block-paragraph\">In dodicesima posizione sulla griglia di partenza, Leclerc si era classificato nono durante le qualificazioni, ma \u00e8 dovuto indietreggiare di tre posti a causa della penalit\u00e0 subita per aver toccato la monoposto di Sergio Perez (Racing Point) nell&#8217;ultima gara nel Bahrein. Il monegasco non ha avuto vita facile in questa corsa, segnata da un strategia singolare della scuderia Ferrari, che ha lasciato Leclerc in pista con le gomme medie durante l&#8217;intervento della Virtual safety car, invece di farlo rientrare ai box per passare agli pneumatici duri.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>&gt;&gt; LEGGI ANCHE:\u00a0<\/strong><a href=\"https:\/\/www.monaco-tribune.com\/it\/2020\/11\/jacky-ickx-ormai-charles-leclerc-e-parte-del-patrimonio-italiano\/\">Intervista a Jacky Ickx: \u201cOrmai Charles Leclerc \u00e8 parte del patrimonio italiano\u201d<\/a><\/p>\n\n<p class=\"wp-block-paragraph\">&#8220;Se devo essere sincero, \u00e8 stata una strategia studiata&#8221;, confessa il pilota, visto che la maggior parte dei concorrenti ha optato per le gomme dure. &#8220;Abbiamo provato una cosa diversa perch\u00e9 sapevamo che se avessimo fatto in modo normale non avremmo potuto ottenere risultati. \u00c8 stato un tentativo disperato e non ha funzionato, senza troppe sorprese&#8221;.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-2021-dans-tous-les-esprits\">Pronto per il 2021<\/h2>\n\n<p class=\"wp-block-paragraph\">Tredicesimo all&#8217;arrivo, il pilota Ferrari non ha portato a casa neanche un punto e ha visto Alex Albon (Red Bull) e Carlos Sainz (McLaren) superarlo nel campionato del mondo piloti. Classificato all&#8217;ottavo posto finale per la stagione 2020, che non rester\u00e0 di certo impressa nella sua memoria, Leclerc \u00e8 gi\u00e0 pronto per affrontare il 2021: &#8220;Apporteremo delle migliorie, prometto che conquister\u00f2 una posizione migliore&#8221;.<\/p>\n\n<hr class=\"wp-block-separator\"\/>\n\n<h3 class=\"has-text-align-center wp-block-heading\" id=\"h-6\"><strong>6\u00b0<\/strong><\/h3>\n\n<hr class=\"wp-block-separator\"\/>\n\n<p class=\"has-text-align-center wp-block-paragraph\">\u00c8 questa <a href=\"https:\/\/www.formula1.com\/en\/results.html\/2020\/team.html\">la posizione della Ferrari<\/a> nel campionato del mondo costruttori. Il risultato peggiore della scuderia italiana degli ultimi 40 anni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la finale di Abu Dhabi della scorsa domenica, si \u00e8 concluso il Gran Premio del 2020. Il pilota Ferrari [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":58072,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1738,1743],"tags":[3348],"post_sectags":[],"post_format":[2478],"class_list":["post-58131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie","category-sport-it","tag-charles-leclerc-it","format-notizia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gran Premio di Abu Dhabi: Charles Leclerc termina in tredicesima posizione<\/title>\n<meta name=\"description\" content=\"Con la finale di Abu Dhabi della scorsa domenica, si \u00e8 concluso il Gran Premio del 2020. Il pilota Ferrari termina in tredicesima posizione, Max\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gran Premio di Abu Dhabi: Charles Leclerc termina in tredicesima posizione - Monaco Tribune\" \/>\n<meta property=\"og:description\" content=\"Con la finale di Abu Dhabi della scorsa domenica, si \u00e8 concluso il Gran Premio del 2020. Il pilota Ferrari termina in tredicesima posizione, Max\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\/\" \/>\n<meta property=\"og:site_name\" content=\"Monaco Tribune\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MonacoTribune\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-14T10:36:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-14T10:40:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2020\/12\/charles-leclerc-ferrari-abu-dhabi.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1366\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Romain Boisaubert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MonacoTribune\" \/>\n<meta name=\"twitter:site\" content=\"@MonacoTribune\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\\\/\"},\"author\":{\"name\":\"Romain Boisaubert\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#\\\/schema\\\/person\\\/330a3732947cf8cb41b2533a0eadd62e\"},\"headline\":\"Gran Premio di Abu Dhabi: Charles Leclerc termina in tredicesima posizione\",\"datePublished\":\"2020-12-14T10:36:56+00:00\",\"dateModified\":\"2020-12-14T10:40:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\\\/\"},\"wordCount\":337,\"publisher\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/charles-leclerc-ferrari-abu-dhabi.jpeg\",\"keywords\":[\"Charles Leclerc\"],\"articleSection\":[\"Notizie\",\"Sport\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\\\/\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\\\/\",\"name\":\"Gran Premio di Abu Dhabi: Charles Leclerc termina in tredicesima posizione\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/charles-leclerc-ferrari-abu-dhabi.jpeg\",\"datePublished\":\"2020-12-14T10:36:56+00:00\",\"dateModified\":\"2020-12-14T10:40:08+00:00\",\"description\":\"Con la finale di Abu Dhabi della scorsa domenica, si \u00e8 concluso il Gran Premio del 2020. Il pilota Ferrari termina in tredicesima posizione, Max\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/charles-leclerc-ferrari-abu-dhabi.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/charles-leclerc-ferrari-abu-dhabi.jpeg\",\"width\":2048,\"height\":1366,\"caption\":\"Scuderia Ferrari\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gran Premio di Abu Dhabi: Charles Leclerc termina in tredicesima posizione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/\",\"name\":\"Monaco Tribune\",\"description\":\"Monaco : actualit\u00e9s \u00e9conomiques, politiques, culturelles et sportives de Monaco et de la French Riviera.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#organization\",\"name\":\"Monaco Tribune\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo-monaco-tribune.png\",\"contentUrl\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo-monaco-tribune.png\",\"width\":1548,\"height\":600,\"caption\":\"Monaco Tribune\"},\"image\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MonacoTribune\",\"https:\\\/\\\/x.com\\\/MonacoTribune\",\"https:\\\/\\\/www.instagram.com\\\/monacotribune\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/monaco-tribune\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCHle1MnG6hw1y4lWKijVbMA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#\\\/schema\\\/person\\\/330a3732947cf8cb41b2533a0eadd62e\",\"name\":\"Romain Boisaubert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8b90d41f1eabd1cbe4cf59e09d8db41a697d51919bf2dfe727589a24a4a4d54?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8b90d41f1eabd1cbe4cf59e09d8db41a697d51919bf2dfe727589a24a4a4d54?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8b90d41f1eabd1cbe4cf59e09d8db41a697d51919bf2dfe727589a24a4a4d54?s=96&d=mm&r=g\",\"caption\":\"Romain Boisaubert\"},\"description\":\"Test bio\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/author\\\/romain-boisaubert\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gran Premio di Abu Dhabi: Charles Leclerc termina in tredicesima posizione","description":"Con la finale di Abu Dhabi della scorsa domenica, si \u00e8 concluso il Gran Premio del 2020. Il pilota Ferrari termina in tredicesima posizione, Max","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\/","og_locale":"it_IT","og_type":"article","og_title":"Gran Premio di Abu Dhabi: Charles Leclerc termina in tredicesima posizione - Monaco Tribune","og_description":"Con la finale di Abu Dhabi della scorsa domenica, si \u00e8 concluso il Gran Premio del 2020. Il pilota Ferrari termina in tredicesima posizione, Max","og_url":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\/","og_site_name":"Monaco Tribune","article_publisher":"https:\/\/www.facebook.com\/MonacoTribune","article_published_time":"2020-12-14T10:36:56+00:00","article_modified_time":"2020-12-14T10:40:08+00:00","og_image":[{"width":2048,"height":1366,"url":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2020\/12\/charles-leclerc-ferrari-abu-dhabi.jpeg","type":"image\/jpeg"}],"author":"Romain Boisaubert","twitter_card":"summary_large_image","twitter_creator":"@MonacoTribune","twitter_site":"@MonacoTribune","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\/#article","isPartOf":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\/"},"author":{"name":"Romain Boisaubert","@id":"https:\/\/www.monaco-tribune.com\/it\/#\/schema\/person\/330a3732947cf8cb41b2533a0eadd62e"},"headline":"Gran Premio di Abu Dhabi: Charles Leclerc termina in tredicesima posizione","datePublished":"2020-12-14T10:36:56+00:00","dateModified":"2020-12-14T10:40:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\/"},"wordCount":337,"publisher":{"@id":"https:\/\/www.monaco-tribune.com\/it\/#organization"},"image":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2020\/12\/charles-leclerc-ferrari-abu-dhabi.jpeg","keywords":["Charles Leclerc"],"articleSection":["Notizie","Sport"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.monaco-tribune.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\/","url":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\/","name":"Gran Premio di Abu Dhabi: Charles Leclerc termina in tredicesima posizione","isPartOf":{"@id":"https:\/\/www.monaco-tribune.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\/#primaryimage"},"image":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2020\/12\/charles-leclerc-ferrari-abu-dhabi.jpeg","datePublished":"2020-12-14T10:36:56+00:00","dateModified":"2020-12-14T10:40:08+00:00","description":"Con la finale di Abu Dhabi della scorsa domenica, si \u00e8 concluso il Gran Premio del 2020. Il pilota Ferrari termina in tredicesima posizione, Max","breadcrumb":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.monaco-tribune.com\/it\/2020\/12\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\/#primaryimage","url":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2020\/12\/charles-leclerc-ferrari-abu-dhabi.jpeg","contentUrl":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2020\/12\/charles-leclerc-ferrari-abu-dhabi.jpeg","width":2048,"height":1366,"caption":"Scuderia Ferrari"},{"@type":"BreadcrumbList","@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/gran-premio-di-abu-dhabi-charles-leclerc-termina-in-tredicesima-posizione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.monaco-tribune.com\/it\/"},{"@type":"ListItem","position":2,"name":"Gran Premio di Abu Dhabi: Charles Leclerc termina in tredicesima posizione"}]},{"@type":"WebSite","@id":"https:\/\/www.monaco-tribune.com\/it\/#website","url":"https:\/\/www.monaco-tribune.com\/it\/","name":"Monaco Tribune","description":"Monaco : actualit\u00e9s \u00e9conomiques, politiques, culturelles et sportives de Monaco et de la French Riviera.","publisher":{"@id":"https:\/\/www.monaco-tribune.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.monaco-tribune.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.monaco-tribune.com\/it\/#organization","name":"Monaco Tribune","url":"https:\/\/www.monaco-tribune.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.monaco-tribune.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2022\/11\/logo-monaco-tribune.png","contentUrl":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2022\/11\/logo-monaco-tribune.png","width":1548,"height":600,"caption":"Monaco Tribune"},"image":{"@id":"https:\/\/www.monaco-tribune.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MonacoTribune","https:\/\/x.com\/MonacoTribune","https:\/\/www.instagram.com\/monacotribune\/","https:\/\/www.linkedin.com\/company\/monaco-tribune","https:\/\/www.youtube.com\/channel\/UCHle1MnG6hw1y4lWKijVbMA"]},{"@type":"Person","@id":"https:\/\/www.monaco-tribune.com\/it\/#\/schema\/person\/330a3732947cf8cb41b2533a0eadd62e","name":"Romain Boisaubert","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f8b90d41f1eabd1cbe4cf59e09d8db41a697d51919bf2dfe727589a24a4a4d54?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f8b90d41f1eabd1cbe4cf59e09d8db41a697d51919bf2dfe727589a24a4a4d54?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f8b90d41f1eabd1cbe4cf59e09d8db41a697d51919bf2dfe727589a24a4a4d54?s=96&d=mm&r=g","caption":"Romain Boisaubert"},"description":"Test bio","url":"https:\/\/www.monaco-tribune.com\/it\/author\/romain-boisaubert\/"}]}},"_links":{"self":[{"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/posts\/58131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/comments?post=58131"}],"version-history":[{"count":0,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/posts\/58131\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/media\/58072"}],"wp:attachment":[{"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/media?parent=58131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/categories?post=58131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/tags?post=58131"},{"taxonomy":"sectag","embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/post_sectags?post=58131"},{"taxonomy":"format","embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/post_format?post=58131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}