{"id":58530,"date":"2020-12-15T19:32:31","date_gmt":"2020-12-15T18:32:31","guid":{"rendered":"https:\/\/www.monaco-tribune.com\/2020\/12\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\/"},"modified":"2020-12-15T19:32:39","modified_gmt":"2020-12-15T18:32:39","slug":"courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito","status":"publish","type":"post","link":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\/","title":{"rendered":"Courchevel, la pista da sci dei milionari, si prepara a un Natale diverso dal solito"},"content":{"rendered":"\n<p><strong>Il comprensorio sciistico numero uno per gli amanti dello sci nel Principato \u00e8 la meta invernale preferita di molti monegaschi e residenti, come Charles Leclerc per esempio. Quest&#8217;anno, per\u00f2, come nelle altre 350 stazioni sciistiche francesi, gli impianti di risalita del pi\u00f9 grande comprensorio del mondo resteranno chiusi per il periodo di Natale.<\/strong><\/p>\n\n<p>Aperta gi\u00e0 dal 5 dicembre, la stazione di lusso \u00e8 stata la prima a istituire un centro di analisi con &#8220;un laboratorio in grado di effettuare 500 tamponi al giorno&#8221;, spiega il sindaco del comune, Jean-Yves Pachod. Purtroppo per\u00f2, le misure sanitarie non sono sufficienti a garantire <a href=\"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/sci-e-covid-19-quando-riapriranno-gli-impianti-di-risalita\/\">l&#8217;apertura degli impianti di risalita<\/a>. &#8220;Un duro colpo&#8221; per Pascal de Thiersant, direttore della societ\u00e0 che gestisce il comprensorio sciistico Les Trois Vall\u00e9es. Appassionato di montagna, originario di Nizza e nipote del primo direttore della stazione sciistica di Auron, Pascal de Thiersant ammette che &#8220;gli incidenti sugli sci non seguono un andamento lineare. Ci possono sicuramente essere dei picchi, che potrebbero essere difficili da gestire se sommati al resto&#8221;.<\/p>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"545\" src=\"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2020\/12\/courchevel-1-1024x545.jpg\" alt=\"Courchevel\" class=\"wp-image-58314\" srcset=\"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2020\/12\/courchevel-1-1024x545.jpg 1024w, https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2020\/12\/courchevel-1-564x300.jpg 564w, https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2020\/12\/courchevel-1.jpg 1192w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Courchevel \u00e8 pronta ad accogliere i visitatori<\/figcaption><\/figure><\/div>\n\n<h2 class=\"wp-block-heading\" id=\"h-doublement-impact-e-entre-crise-sanitaire-et-brexit\">Un doppio colpo, tra crisi sanitaria e Brexit<\/h2>\n\n<p>&#8220;A inizio dicembre, abbiamo stimato che, se aprissimo a met\u00e0 gennaio, subiremmo un calo nell&#8217;affluenza del 55% rispetto al 2019&#8221; ha spiegato nel dettaglio. Si prospetta una stagione difficile per Courchevel, colpita su due versanti, sia dalla crisi sanitaria, sia dalla Brexit. Il problema infatti, \u00e8 che in questa stazione che conta 2400 abitanti fuori stagione e forse 15 volte tanto in inverno, la clientela internazionale rappresenta pi\u00f9 del 60%, di cui 40% inglesi, 8% russi e qualche belga.<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\" id=\"h-je-ne-vois-pas-nos-clients-d-jeuner-des-sandwichs-sur-les-pistes-puis-rentrer-se-confiner-dans-leur-chambre-17h\"><p>Non credo che i nostri clienti si accontenterebbero di mangiare un panino sulle piste e poi chiudersi in camera alle 17:00<\/p><\/blockquote>\n\n<h2 class=\"wp-block-heading\" id=\"h-tr-s-peu-d-h-tels-ouverts-avant-2021\">Pochissimi hotel aperti per la fine del 2020<\/h2>\n\n<p>Molti hotel della stazione, inoltre, hanno deciso di non aprire prima di gennaio, come Jean-Claude Lavorel, responsabile del Le Chabichou, del Les Suites de la Potini\u00e8re e del Grand Hotel de Courchevel. &#8220;Senza ristoranti e bar \u00e8 impensabile poter aprire. Non credo che i nostri clienti si accontenterebbero di mangiare un panino sulle piste e poi chiudersi in camera alle 17:00&#8221;.<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Il nostro obiettivo \u00e8 restare aperti il pi\u00f9 possibile, magari fino a fine aprile<\/p><\/blockquote>\n\n<p>Inoltre, prevedere l&#8217;apertura dei suoi tre hotel, comporta una somma enorme di stipendi che inizialmente ha dovuto assumersi, su consiglio del ministro del lavoro, per poi concedere ai dipendenti un orario ridotto con disoccupazione parziale. &#8220;Parliamo, in totale, di 200 dipendenti&#8221;, dichiara. Ciononostante, l&#8217;amministratore delegato del gruppo Lavorel non si \u00e8 dato per vinto: &#8220;Siamo pronti per il 20 gennaio. Se la chiusura dei ristoranti viene prolungata, forse dovremo rivedere i nostri piani. Ma l&#8217;obiettivo, per recuperare la stagione, \u00e8 di restare aperti il pi\u00f9 possibile, magari fino a fine aprile&#8221;.<\/p>\n\n<p><strong>&gt;&gt; LEGGI ANCHE: <\/strong><a href=\"https:\/\/www.monaco-tribune.com\/it\/2020\/11\/lindustria-degli-yacht-resta-a-galla-nonostante-la-pandemia\/\">L\u2019industria degli yacht resta \u201ca galla\u201d nonostante la pandemia<\/a><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-vers-un-tourisme-4-saisons\">Verso un turismo 4 stagioni?<\/h2>\n\n<p>Consapevoli che l&#8217;ecosistema della montagna si basa principalmente sullo sci alpino, i professionisti del settore hanno guardato alla crisi come a una possibilit\u00e0 per potersi reinventare e accelerare la transizione verso un turismo 4 stagioni, come spiega Pascal de Thiersant: &#8220;Quest&#8217;estate, a Courchevel, c&#8217;\u00e8 stata una bella affluenza di visitatori venuti a scoprire le montagne fuori stagione. Il nuovo itinerario del Col de la Loze (2304 m), punto saliente del Tour de France 2020, ha avuto gi\u00e0 un successo incredibile. Ciononostante, a Courchevel non ci sono ancora abbastanza hotel e ristoranti aperti per poter accontentare i gusti di tutti&#8221;. Siamo certi che, in futuro, saranno sempre di pi\u00f9 gli hotel e i ristoranti che scommetteranno anche sulla stagione estiva.&#13;\n&#13;\nTraduzione a cura di <a href=\"http:\/\/valentinaaliatranslator.com\">Valentina Alia<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il comprensorio sciistico numero uno per gli amanti dello sci nel Principato \u00e8 la meta invernale preferita di molti monegaschi [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":58293,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1826,1738,1752],"tags":[2886],"post_sectags":[],"post_format":[2478],"class_list":["post-58530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-nostra-scelta","category-notizie","category-societa","tag-covid-19-it","format-notizia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Courchevel, la pista da sci dei milionari, si prepara a un Natale diverso dal solito<\/title>\n<meta name=\"description\" content=\"Il comprensorio sciistico numero uno per gli amanti dello sci nel Principato \u00e8 la meta invernale preferita di molti monegaschi e residenti, come Charles\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Courchevel, la pista da sci dei milionari, si prepara a un Natale diverso dal solito - Monaco Tribune\" \/>\n<meta property=\"og:description\" content=\"Il comprensorio sciistico numero uno per gli amanti dello sci nel Principato \u00e8 la meta invernale preferita di molti monegaschi e residenti, come Charles\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\/\" \/>\n<meta property=\"og:site_name\" content=\"Monaco Tribune\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MonacoTribune\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-15T18:32:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-15T18:32:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2020\/12\/courchevel-1850-ouverture-remonte\u0301s-me\u0301caniques-monaco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"939\" \/>\n\t<meta property=\"og:image:height\" content=\"528\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marjorie Modi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MonacoTribune\" \/>\n<meta name=\"twitter:site\" content=\"@MonacoTribune\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\\\/\"},\"author\":{\"name\":\"Marjorie Modi\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#\\\/schema\\\/person\\\/5b18add85fa272c0fa24f32c6d1302e1\"},\"headline\":\"Courchevel, la pista da sci dei milionari, si prepara a un Natale diverso dal solito\",\"datePublished\":\"2020-12-15T18:32:31+00:00\",\"dateModified\":\"2020-12-15T18:32:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\\\/\"},\"wordCount\":600,\"publisher\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/courchevel-1850-ouverture-remonte\u0301s-me\u0301caniques-monaco.jpg\",\"keywords\":[\"Covid-19\"],\"articleSection\":[\"La nostra scelta\",\"Notizie\",\"Societ\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\\\/\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\\\/\",\"name\":\"Courchevel, la pista da sci dei milionari, si prepara a un Natale diverso dal solito\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/courchevel-1850-ouverture-remonte\u0301s-me\u0301caniques-monaco.jpg\",\"datePublished\":\"2020-12-15T18:32:31+00:00\",\"dateModified\":\"2020-12-15T18:32:39+00:00\",\"description\":\"Il comprensorio sciistico numero uno per gli amanti dello sci nel Principato \u00e8 la meta invernale preferita di molti monegaschi e residenti, come Charles\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/courchevel-1850-ouverture-remonte\u0301s-me\u0301caniques-monaco.jpg\",\"contentUrl\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/courchevel-1850-ouverture-remonte\u0301s-me\u0301caniques-monaco.jpg\",\"width\":939,\"height\":528,\"caption\":\"Courchevel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/2020\\\/12\\\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Courchevel, la pista da sci dei milionari, si prepara a un Natale diverso dal solito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/\",\"name\":\"Monaco Tribune\",\"description\":\"Monaco : actualit\u00e9s \u00e9conomiques, politiques, culturelles et sportives de Monaco et de la French Riviera.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#organization\",\"name\":\"Monaco Tribune\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo-monaco-tribune.png\",\"contentUrl\":\"https:\\\/\\\/www.monaco-tribune.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo-monaco-tribune.png\",\"width\":1548,\"height\":600,\"caption\":\"Monaco Tribune\"},\"image\":{\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MonacoTribune\",\"https:\\\/\\\/x.com\\\/MonacoTribune\",\"https:\\\/\\\/www.instagram.com\\\/monacotribune\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/monaco-tribune\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCHle1MnG6hw1y4lWKijVbMA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/#\\\/schema\\\/person\\\/5b18add85fa272c0fa24f32c6d1302e1\",\"name\":\"Marjorie Modi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca5506f0a36bb5f3a7a88da16cc9bf1a2eccaa24c9f121a4312c9d903e503815?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca5506f0a36bb5f3a7a88da16cc9bf1a2eccaa24c9f121a4312c9d903e503815?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca5506f0a36bb5f3a7a88da16cc9bf1a2eccaa24c9f121a4312c9d903e503815?s=96&d=mm&r=g\",\"caption\":\"Marjorie Modi\"},\"url\":\"https:\\\/\\\/www.monaco-tribune.com\\\/it\\\/author\\\/marjoriemodi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Courchevel, la pista da sci dei milionari, si prepara a un Natale diverso dal solito","description":"Il comprensorio sciistico numero uno per gli amanti dello sci nel Principato \u00e8 la meta invernale preferita di molti monegaschi e residenti, come Charles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\/","og_locale":"it_IT","og_type":"article","og_title":"Courchevel, la pista da sci dei milionari, si prepara a un Natale diverso dal solito - Monaco Tribune","og_description":"Il comprensorio sciistico numero uno per gli amanti dello sci nel Principato \u00e8 la meta invernale preferita di molti monegaschi e residenti, come Charles","og_url":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\/","og_site_name":"Monaco Tribune","article_publisher":"https:\/\/www.facebook.com\/MonacoTribune","article_published_time":"2020-12-15T18:32:31+00:00","article_modified_time":"2020-12-15T18:32:39+00:00","og_image":[{"width":939,"height":528,"url":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2020\/12\/courchevel-1850-ouverture-remonte\u0301s-me\u0301caniques-monaco.jpg","type":"image\/jpeg"}],"author":"Marjorie Modi","twitter_card":"summary_large_image","twitter_creator":"@MonacoTribune","twitter_site":"@MonacoTribune","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\/#article","isPartOf":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\/"},"author":{"name":"Marjorie Modi","@id":"https:\/\/www.monaco-tribune.com\/it\/#\/schema\/person\/5b18add85fa272c0fa24f32c6d1302e1"},"headline":"Courchevel, la pista da sci dei milionari, si prepara a un Natale diverso dal solito","datePublished":"2020-12-15T18:32:31+00:00","dateModified":"2020-12-15T18:32:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\/"},"wordCount":600,"publisher":{"@id":"https:\/\/www.monaco-tribune.com\/it\/#organization"},"image":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\/#primaryimage"},"thumbnailUrl":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2020\/12\/courchevel-1850-ouverture-remonte\u0301s-me\u0301caniques-monaco.jpg","keywords":["Covid-19"],"articleSection":["La nostra scelta","Notizie","Societ\u00e0"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.monaco-tribune.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\/","url":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\/","name":"Courchevel, la pista da sci dei milionari, si prepara a un Natale diverso dal solito","isPartOf":{"@id":"https:\/\/www.monaco-tribune.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\/#primaryimage"},"image":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\/#primaryimage"},"thumbnailUrl":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2020\/12\/courchevel-1850-ouverture-remonte\u0301s-me\u0301caniques-monaco.jpg","datePublished":"2020-12-15T18:32:31+00:00","dateModified":"2020-12-15T18:32:39+00:00","description":"Il comprensorio sciistico numero uno per gli amanti dello sci nel Principato \u00e8 la meta invernale preferita di molti monegaschi e residenti, come Charles","breadcrumb":{"@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.monaco-tribune.com\/it\/2020\/12\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\/#primaryimage","url":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2020\/12\/courchevel-1850-ouverture-remonte\u0301s-me\u0301caniques-monaco.jpg","contentUrl":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2020\/12\/courchevel-1850-ouverture-remonte\u0301s-me\u0301caniques-monaco.jpg","width":939,"height":528,"caption":"Courchevel"},{"@type":"BreadcrumbList","@id":"https:\/\/www.monaco-tribune.com\/it\/2020\/12\/courchevel-la-pista-da-sci-dei-milionari-si-prepara-a-un-natale-diverso-dal-solito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.monaco-tribune.com\/it\/"},{"@type":"ListItem","position":2,"name":"Courchevel, la pista da sci dei milionari, si prepara a un Natale diverso dal solito"}]},{"@type":"WebSite","@id":"https:\/\/www.monaco-tribune.com\/it\/#website","url":"https:\/\/www.monaco-tribune.com\/it\/","name":"Monaco Tribune","description":"Monaco : actualit\u00e9s \u00e9conomiques, politiques, culturelles et sportives de Monaco et de la French Riviera.","publisher":{"@id":"https:\/\/www.monaco-tribune.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.monaco-tribune.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.monaco-tribune.com\/it\/#organization","name":"Monaco Tribune","url":"https:\/\/www.monaco-tribune.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.monaco-tribune.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2022\/11\/logo-monaco-tribune.png","contentUrl":"https:\/\/www.monaco-tribune.com\/wp-content\/uploads\/2022\/11\/logo-monaco-tribune.png","width":1548,"height":600,"caption":"Monaco Tribune"},"image":{"@id":"https:\/\/www.monaco-tribune.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MonacoTribune","https:\/\/x.com\/MonacoTribune","https:\/\/www.instagram.com\/monacotribune\/","https:\/\/www.linkedin.com\/company\/monaco-tribune","https:\/\/www.youtube.com\/channel\/UCHle1MnG6hw1y4lWKijVbMA"]},{"@type":"Person","@id":"https:\/\/www.monaco-tribune.com\/it\/#\/schema\/person\/5b18add85fa272c0fa24f32c6d1302e1","name":"Marjorie Modi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ca5506f0a36bb5f3a7a88da16cc9bf1a2eccaa24c9f121a4312c9d903e503815?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ca5506f0a36bb5f3a7a88da16cc9bf1a2eccaa24c9f121a4312c9d903e503815?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca5506f0a36bb5f3a7a88da16cc9bf1a2eccaa24c9f121a4312c9d903e503815?s=96&d=mm&r=g","caption":"Marjorie Modi"},"url":"https:\/\/www.monaco-tribune.com\/it\/author\/marjoriemodi\/"}]}},"_links":{"self":[{"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/posts\/58530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/comments?post=58530"}],"version-history":[{"count":0,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/posts\/58530\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/media\/58293"}],"wp:attachment":[{"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/media?parent=58530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/categories?post=58530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/tags?post=58530"},{"taxonomy":"sectag","embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/post_sectags?post=58530"},{"taxonomy":"format","embeddable":true,"href":"https:\/\/www.monaco-tribune.com\/it\/wp-json\/wp\/v2\/post_format?post=58530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}